{"id":590,"date":"2021-01-27T10:18:50","date_gmt":"2021-01-27T09:18:50","guid":{"rendered":"https:\/\/www.medisocial.it\/annapaolacavalieri\/?p=590"},"modified":"2021-01-27T10:29:45","modified_gmt":"2021-01-27T09:29:45","slug":"cordone-ombelicale-tempi-del-taglio","status":"publish","type":"post","link":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/","title":{"rendered":"Cordone ombelicale: tempi del taglio"},"content":{"rendered":"<p><strong>Cordone ombelicale: tempi del taglio<br \/>\n<\/strong><br \/>\nAspettare almeno un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in un migliore neurosviluppo del bambino diversi anni dopo.<\/p>\n<p>C&#8217;\u00e8 una crescente evidenza scientifica che tutti i bambini, quelli nati a termine e quelli nati precocemente, traggano beneficio dal ricevere sangue extra dalla placenta alla nascita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-591\" src=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-300x225.jpg\" alt=\"Cordone ombelicale\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-300x225.jpg 300w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-1024x768.jpg 1024w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-768x576.jpg 768w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-1536x1152.jpg 1536w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Ritardare il clampaggio del cordone consente il trasferimento di pi\u00f9 sangue dalla placenta al neonato, a volte aumentando il volume del sangue del bambino fino a un terzo.<\/p>\n<p>Il ferro nel sangue aumenta l&#8217;accumulo di ferro nei bambini e il ferro \u00e8 essenziale per uno sviluppo sano del cervello.<\/p>\n<p>Il sangue extra alla nascita aiuta inoltre il bambino ad affrontare meglio il passaggio dal grembo materno, dove tutto \u00e8 fornito dalla placenta e dalla madre, al mondo esterno.<\/p>\n<p>Se questa pratica \u00e8 relativamente semplice nel parto vaginale, un po\u2019 pi\u00f9 complesso \u00e8 applicarla nel taglio cesareo.<\/p>\n<p>Io personalmente nel taglio cesareo cerco di aspettare sempre un po\u2019 prima di tagliare il cordone ombelicale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-593\" src=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-189x300.jpeg\" alt=\"Cordone ombelicale\" width=\"189\" height=\"300\" srcset=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-189x300.jpeg 189w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-645x1024.jpeg 645w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-768x1219.jpeg 768w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale-968x1536.jpeg 968w, https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg 1008w\" sizes=\"(max-width: 189px) 100vw, 189px\" \/><\/p>\n<p>Nella foto sto sentendo con la mano le pulsazioni attraverso il cordone del bimbo appena nato.<\/p>\n<p>Quando tali pulsazioni si fanno pi\u00f9 deboli, indice che il flusso di sangue dalla placenta al bimbo si \u00e8 ridotto, procedo con il taglio del cordone.<\/p>\n<p>Nel parto spontaneo si pu\u00f2 attendere finch\u00e9 le pulsazioni nel cordone non cessino completamente.<\/p>\n<p>Per ulteriori informazioni e per fissare un appuntamento per una visita, andate nella sezione <strong><a href=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/contatti\/\">Contatti<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cordone ombelicale: tempi del taglio Aspettare almeno un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in un migliore neurosviluppo del bambino diversi anni dopo. C&#8217;\u00e8 una crescente evidenza scientifica che tutti i bambini, quelli nati a termine e quelli nati precocemente, traggano beneficio dal ricevere sangue extra dalla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[224,225,222,173,130,223,131],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cordone ombelicale: tempi del taglio - Dott.ssa Anna Paola Cavalieri<\/title>\n<meta name=\"description\" content=\"Cordone ombelicale Aspettare un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in migliore neurosviluppo del bambino\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cordone ombelicale: tempi del taglio - Dott.ssa Anna Paola Cavalieri\" \/>\n<meta property=\"og:description\" content=\"Cordone ombelicale Aspettare un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in migliore neurosviluppo del bambino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/\" \/>\n<meta property=\"og:site_name\" content=\"Dott.ssa Anna Paola Cavalieri\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T09:18:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-27T09:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"medisocial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"medisocial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/\"},\"author\":{\"name\":\"medisocial\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/person\/1cd0bfb9ce49bd43804584df39ef2c91\"},\"headline\":\"Cordone ombelicale: tempi del taglio\",\"datePublished\":\"2021-01-27T09:18:50+00:00\",\"dateModified\":\"2021-01-27T09:29:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg\",\"keywords\":[\"cesareodolce\",\"clampaggioritardato\",\"cordoneombelicale\",\"Dott.ssa Anna Paola Cavalieri\",\"ginecologaroma\",\"partorispettato\",\"specialistaginecologiaroma\"],\"articleSection\":[\"Articoli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/\",\"url\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/\",\"name\":\"Cordone ombelicale: tempi del taglio - Dott.ssa Anna Paola Cavalieri\",\"isPartOf\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg\",\"datePublished\":\"2021-01-27T09:18:50+00:00\",\"dateModified\":\"2021-01-27T09:29:45+00:00\",\"description\":\"Cordone ombelicale Aspettare un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in migliore neurosviluppo del bambino\",\"breadcrumb\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage\",\"url\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg\",\"contentUrl\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg\",\"width\":1008,\"height\":1600,\"caption\":\"Cordone ombelicale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cordone ombelicale: tempi del taglio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#website\",\"url\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/\",\"name\":\"Dott.ssa Anna Paola Cavalieri\",\"description\":\"Specialista in Ostetricia e Ginecologia - Roma\",\"publisher\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#organization\",\"name\":\"Dott.ssa Anna Paola Cavalieri\",\"url\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2019\/06\/logo7.jpg\",\"contentUrl\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2019\/06\/logo7.jpg\",\"width\":242,\"height\":99,\"caption\":\"Dott.ssa Anna Paola Cavalieri\"},\"image\":{\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/person\/1cd0bfb9ce49bd43804584df39ef2c91\",\"name\":\"medisocial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efa9393110d3610a15f45429c6613084?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efa9393110d3610a15f45429c6613084?s=96&d=mm&r=g\",\"caption\":\"medisocial\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cordone ombelicale: tempi del taglio - Dott.ssa Anna Paola Cavalieri","description":"Cordone ombelicale Aspettare un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in migliore neurosviluppo del bambino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/","og_locale":"it_IT","og_type":"article","og_title":"Cordone ombelicale: tempi del taglio - Dott.ssa Anna Paola Cavalieri","og_description":"Cordone ombelicale Aspettare un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in migliore neurosviluppo del bambino","og_url":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/","og_site_name":"Dott.ssa Anna Paola Cavalieri","article_published_time":"2021-01-27T09:18:50+00:00","article_modified_time":"2021-01-27T09:29:45+00:00","og_image":[{"width":1008,"height":1600,"url":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg","type":"image\/jpeg"}],"author":"medisocial","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"medisocial","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#article","isPartOf":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/"},"author":{"name":"medisocial","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/person\/1cd0bfb9ce49bd43804584df39ef2c91"},"headline":"Cordone ombelicale: tempi del taglio","datePublished":"2021-01-27T09:18:50+00:00","dateModified":"2021-01-27T09:29:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#organization"},"image":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg","keywords":["cesareodolce","clampaggioritardato","cordoneombelicale","Dott.ssa Anna Paola Cavalieri","ginecologaroma","partorispettato","specialistaginecologiaroma"],"articleSection":["Articoli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/","url":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/","name":"Cordone ombelicale: tempi del taglio - Dott.ssa Anna Paola Cavalieri","isPartOf":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage"},"image":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg","datePublished":"2021-01-27T09:18:50+00:00","dateModified":"2021-01-27T09:29:45+00:00","description":"Cordone ombelicale Aspettare un paio di minuti in pi\u00f9 nel tagliare il cordone ombelicale alla nascita pu\u00f2 tradursi in migliore neurosviluppo del bambino","breadcrumb":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#primaryimage","url":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg","contentUrl":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2021\/01\/Cordone-ombelicale.jpeg","width":1008,"height":1600,"caption":"Cordone ombelicale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/2021\/01\/27\/cordone-ombelicale-tempi-del-taglio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.medisocial.it\/annapaolacavalieri\/"},{"@type":"ListItem","position":2,"name":"Cordone ombelicale: tempi del taglio"}]},{"@type":"WebSite","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#website","url":"https:\/\/www.medisocial.it\/annapaolacavalieri\/","name":"Dott.ssa Anna Paola Cavalieri","description":"Specialista in Ostetricia e Ginecologia - Roma","publisher":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medisocial.it\/annapaolacavalieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#organization","name":"Dott.ssa Anna Paola Cavalieri","url":"https:\/\/www.medisocial.it\/annapaolacavalieri\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/logo\/image\/","url":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2019\/06\/logo7.jpg","contentUrl":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-content\/uploads\/2019\/06\/logo7.jpg","width":242,"height":99,"caption":"Dott.ssa Anna Paola Cavalieri"},"image":{"@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/person\/1cd0bfb9ce49bd43804584df39ef2c91","name":"medisocial","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.medisocial.it\/annapaolacavalieri\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efa9393110d3610a15f45429c6613084?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efa9393110d3610a15f45429c6613084?s=96&d=mm&r=g","caption":"medisocial"}}]}},"_links":{"self":[{"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/posts\/590"}],"collection":[{"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":1,"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"predecessor-version":[{"id":594,"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/posts\/590\/revisions\/594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/media\/593"}],"wp:attachment":[{"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medisocial.it\/annapaolacavalieri\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}